{"id":3502,"date":"2018-07-04T09:51:31","date_gmt":"2018-07-04T07:51:31","guid":{"rendered":"https:\/\/kzgd-dev.dev2.de\/?p=3502"},"modified":"2019-11-20T16:23:53","modified_gmt":"2019-11-20T15:23:53","slug":"book-presentation-dachauer-gedenkorte-zwischen-vergessen-und-erinnern","status":"publish","type":"post","link":"https:\/\/www.kz-gedenkstaette-dachau.de\/en\/coming-dates\/book-presentation-dachauer-gedenkorte-zwischen-vergessen-und-erinnern\/","title":{"rendered":"Book Presentation Dachauer Gedenkorte zwischen Vergessen und Erinnern"},"content":{"rendered":"<div class=\"inside\">\n<div id=\"events-schwenke\" class=\"mod_article block\">\n<div class=\"ce_text block\">\n<h1>Book Presentation Dachauer Gedenkorte zwischen Vergessen und Erinnern<\/h1>\n<div class=\"image_container float_right\" style=\"padding: 5px 0px 5px 5px; float: right;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kz-gedenkstaette-dachau.de\/wp-content\/uploads\/bilder\/html\/Buch Schwenke-ed64d1da.jpg\" alt=\"Book cover Kerstin Schwenke\" width=\"170\" height=\"250\" \/><\/p>\n<div class=\"caption\">Marco Coslovich<\/div>\n<\/div>\n<p>On<br \/>\nThursday, December 1 2011, Kerstin Schwenke, a member of the Education<br \/>\nDepartment at the Dachau Concentration Camp Memorial Site, presents her study <em>Dachauer Gedenkorte zwischen Vergessen und<br \/>\nErinnern \u2013 Die Massengr\u00e4ber am Leitenberg und der ehemalige SS-Schie\u00dfplatz bei<br \/>\nHebertshausen nach 1945<\/em>. The presentation takes place in<br \/>\ncooperation with the Protestant Church of Reconciliation, where it shall also<br \/>\nbegin at 7:30 p.m. Besides the Dachau Concentration Camp Memorial Site, opened<br \/>\nin 1965 and visited by several hundreds of thousands persons from across the<br \/>\nglobe annually, there are two less well-known places of remembrance in Dachau:<br \/>\nthe Leitenberg Memorial Cemetery, where the graves of over 7,400 dead from the<br \/>\nDachau concentration camp are to be found, and the former SS shooting range at<br \/>\nHebertshausen, where some 4,000 Soviet prisoners of war were murdered in<br \/>\n1941\/42. Published in the series \u201cDachauer Diskurse\u201d, the work shows how the<br \/>\nforms of remembrance at both locations have changed over the decades.<\/p>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Book Presentation Dachauer Gedenkorte zwischen Vergessen und Erinnern Marco Coslovich On Thursday, December 1 2011, Kerstin Schwenke, a member of the Education Department at the Dachau Concentration Camp Memorial Site, presents her study Dachauer Gedenkorte zwischen Vergessen und Erinnern \u2013 Die Massengr\u00e4ber am Leitenberg und der ehemalige SS-Schie\u00dfplatz bei Hebertshausen nach 1945. The presentation takes&#8230; <a class=\"view-article\" href=\"https:\/\/www.kz-gedenkstaette-dachau.de\/en\/coming-dates\/book-presentation-dachauer-gedenkorte-zwischen-vergessen-und-erinnern\/\">View Article<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-3502","post","type-post","status-publish","format-standard","hentry","category-coming-dates"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Book Presentation Dachauer Gedenkorte zwischen Vergessen und Erinnern - KZ Gedenkst\u00e4tte Dachau<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.kz-gedenkstaette-dachau.de\/en\/coming-dates\/book-presentation-dachauer-gedenkorte-zwischen-vergessen-und-erinnern\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Book Presentation Dachauer Gedenkorte zwischen Vergessen und Erinnern - KZ Gedenkst\u00e4tte Dachau\" \/>\n<meta property=\"og:description\" content=\"Book Presentation Dachauer Gedenkorte zwischen Vergessen und Erinnern Marco Coslovich On Thursday, December 1 2011, Kerstin Schwenke, a member of the Education Department at the Dachau Concentration Camp Memorial Site, presents her study Dachauer Gedenkorte zwischen Vergessen und Erinnern \u2013 Die Massengr\u00e4ber am Leitenberg und der ehemalige SS-Schie\u00dfplatz bei Hebertshausen nach 1945. The presentation takes... View Article\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.kz-gedenkstaette-dachau.de\/en\/coming-dates\/book-presentation-dachauer-gedenkorte-zwischen-vergessen-und-erinnern\/\" \/>\n<meta property=\"og:site_name\" content=\"KZ Gedenkst\u00e4tte Dachau\" \/>\n<meta property=\"article:published_time\" content=\"2018-07-04T07:51:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-11-20T15:23:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.kz-gedenkstaette-dachau.de\/wp-content\/uploads\/bilder\/html\/Buch%20Schwenke-ed64d1da.jpg\" \/>\n<meta name=\"author\" content=\"neodesign\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"neodesign\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.kz-gedenkstaette-dachau.de\\\/en\\\/coming-dates\\\/book-presentation-dachauer-gedenkorte-zwischen-vergessen-und-erinnern\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.kz-gedenkstaette-dachau.de\\\/en\\\/coming-dates\\\/book-presentation-dachauer-gedenkorte-zwischen-vergessen-und-erinnern\\\/\"},\"author\":{\"name\":\"neodesign\",\"@id\":\"https:\\\/\\\/www.kz-gedenkstaette-dachau.de\\\/#\\\/schema\\\/person\\\/24134f889baf12937f773e1ef2ed9b39\"},\"headline\":\"Book Presentation Dachauer Gedenkorte zwischen Vergessen und Erinnern\",\"datePublished\":\"2018-07-04T07:51:31+00:00\",\"dateModified\":\"2019-11-20T15:23:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.kz-gedenkstaette-dachau.de\\\/en\\\/coming-dates\\\/book-presentation-dachauer-gedenkorte-zwischen-vergessen-und-erinnern\\\/\"},\"wordCount\":168,\"articleSection\":[\"Coming Dates\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.kz-gedenkstaette-dachau.de\\\/en\\\/coming-dates\\\/book-presentation-dachauer-gedenkorte-zwischen-vergessen-und-erinnern\\\/\",\"url\":\"https:\\\/\\\/www.kz-gedenkstaette-dachau.de\\\/en\\\/coming-dates\\\/book-presentation-dachauer-gedenkorte-zwischen-vergessen-und-erinnern\\\/\",\"name\":\"Book Presentation Dachauer Gedenkorte zwischen Vergessen und Erinnern - KZ Gedenkst\u00e4tte Dachau\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.kz-gedenkstaette-dachau.de\\\/#website\"},\"datePublished\":\"2018-07-04T07:51:31+00:00\",\"dateModified\":\"2019-11-20T15:23:53+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.kz-gedenkstaette-dachau.de\\\/#\\\/schema\\\/person\\\/24134f889baf12937f773e1ef2ed9b39\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.kz-gedenkstaette-dachau.de\\\/en\\\/coming-dates\\\/book-presentation-dachauer-gedenkorte-zwischen-vergessen-und-erinnern\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.kz-gedenkstaette-dachau.de\\\/en\\\/coming-dates\\\/book-presentation-dachauer-gedenkorte-zwischen-vergessen-und-erinnern\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.kz-gedenkstaette-dachau.de\\\/en\\\/coming-dates\\\/book-presentation-dachauer-gedenkorte-zwischen-vergessen-und-erinnern\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.kz-gedenkstaette-dachau.de\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Book Presentation Dachauer Gedenkorte zwischen Vergessen und Erinnern\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.kz-gedenkstaette-dachau.de\\\/#website\",\"url\":\"https:\\\/\\\/www.kz-gedenkstaette-dachau.de\\\/\",\"name\":\"KZ Gedenkst\u00e4tte Dachau\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.kz-gedenkstaette-dachau.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.kz-gedenkstaette-dachau.de\\\/#\\\/schema\\\/person\\\/24134f889baf12937f773e1ef2ed9b39\",\"name\":\"neodesign\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/048463e9658ed41af53c71679c66426fb09feff4cf8eaa91ccda42ad67530851?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/048463e9658ed41af53c71679c66426fb09feff4cf8eaa91ccda42ad67530851?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/048463e9658ed41af53c71679c66426fb09feff4cf8eaa91ccda42ad67530851?s=96&d=mm&r=g\",\"caption\":\"neodesign\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Book Presentation Dachauer Gedenkorte zwischen Vergessen und Erinnern - KZ Gedenkst\u00e4tte Dachau","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.kz-gedenkstaette-dachau.de\/en\/coming-dates\/book-presentation-dachauer-gedenkorte-zwischen-vergessen-und-erinnern\/","og_locale":"en_US","og_type":"article","og_title":"Book Presentation Dachauer Gedenkorte zwischen Vergessen und Erinnern - KZ Gedenkst\u00e4tte Dachau","og_description":"Book Presentation Dachauer Gedenkorte zwischen Vergessen und Erinnern Marco Coslovich On Thursday, December 1 2011, Kerstin Schwenke, a member of the Education Department at the Dachau Concentration Camp Memorial Site, presents her study Dachauer Gedenkorte zwischen Vergessen und Erinnern \u2013 Die Massengr\u00e4ber am Leitenberg und der ehemalige SS-Schie\u00dfplatz bei Hebertshausen nach 1945. The presentation takes... View Article","og_url":"https:\/\/www.kz-gedenkstaette-dachau.de\/en\/coming-dates\/book-presentation-dachauer-gedenkorte-zwischen-vergessen-und-erinnern\/","og_site_name":"KZ Gedenkst\u00e4tte Dachau","article_published_time":"2018-07-04T07:51:31+00:00","article_modified_time":"2019-11-20T15:23:53+00:00","og_image":[{"url":"https:\/\/www.kz-gedenkstaette-dachau.de\/wp-content\/uploads\/bilder\/html\/Buch Schwenke-ed64d1da.jpg","type":"","width":"","height":""}],"author":"neodesign","twitter_card":"summary_large_image","twitter_misc":{"Written by":"neodesign","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.kz-gedenkstaette-dachau.de\/en\/coming-dates\/book-presentation-dachauer-gedenkorte-zwischen-vergessen-und-erinnern\/#article","isPartOf":{"@id":"https:\/\/www.kz-gedenkstaette-dachau.de\/en\/coming-dates\/book-presentation-dachauer-gedenkorte-zwischen-vergessen-und-erinnern\/"},"author":{"name":"neodesign","@id":"https:\/\/www.kz-gedenkstaette-dachau.de\/#\/schema\/person\/24134f889baf12937f773e1ef2ed9b39"},"headline":"Book Presentation Dachauer Gedenkorte zwischen Vergessen und Erinnern","datePublished":"2018-07-04T07:51:31+00:00","dateModified":"2019-11-20T15:23:53+00:00","mainEntityOfPage":{"@id":"https:\/\/www.kz-gedenkstaette-dachau.de\/en\/coming-dates\/book-presentation-dachauer-gedenkorte-zwischen-vergessen-und-erinnern\/"},"wordCount":168,"articleSection":["Coming Dates"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.kz-gedenkstaette-dachau.de\/en\/coming-dates\/book-presentation-dachauer-gedenkorte-zwischen-vergessen-und-erinnern\/","url":"https:\/\/www.kz-gedenkstaette-dachau.de\/en\/coming-dates\/book-presentation-dachauer-gedenkorte-zwischen-vergessen-und-erinnern\/","name":"Book Presentation Dachauer Gedenkorte zwischen Vergessen und Erinnern - KZ Gedenkst\u00e4tte Dachau","isPartOf":{"@id":"https:\/\/www.kz-gedenkstaette-dachau.de\/#website"},"datePublished":"2018-07-04T07:51:31+00:00","dateModified":"2019-11-20T15:23:53+00:00","author":{"@id":"https:\/\/www.kz-gedenkstaette-dachau.de\/#\/schema\/person\/24134f889baf12937f773e1ef2ed9b39"},"breadcrumb":{"@id":"https:\/\/www.kz-gedenkstaette-dachau.de\/en\/coming-dates\/book-presentation-dachauer-gedenkorte-zwischen-vergessen-und-erinnern\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.kz-gedenkstaette-dachau.de\/en\/coming-dates\/book-presentation-dachauer-gedenkorte-zwischen-vergessen-und-erinnern\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.kz-gedenkstaette-dachau.de\/en\/coming-dates\/book-presentation-dachauer-gedenkorte-zwischen-vergessen-und-erinnern\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.kz-gedenkstaette-dachau.de\/en\/"},{"@type":"ListItem","position":2,"name":"Book Presentation Dachauer Gedenkorte zwischen Vergessen und Erinnern"}]},{"@type":"WebSite","@id":"https:\/\/www.kz-gedenkstaette-dachau.de\/#website","url":"https:\/\/www.kz-gedenkstaette-dachau.de\/","name":"KZ Gedenkst\u00e4tte Dachau","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.kz-gedenkstaette-dachau.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.kz-gedenkstaette-dachau.de\/#\/schema\/person\/24134f889baf12937f773e1ef2ed9b39","name":"neodesign","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/048463e9658ed41af53c71679c66426fb09feff4cf8eaa91ccda42ad67530851?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/048463e9658ed41af53c71679c66426fb09feff4cf8eaa91ccda42ad67530851?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/048463e9658ed41af53c71679c66426fb09feff4cf8eaa91ccda42ad67530851?s=96&d=mm&r=g","caption":"neodesign"}}]}},"_links":{"self":[{"href":"https:\/\/www.kz-gedenkstaette-dachau.de\/en\/wp-json\/wp\/v2\/posts\/3502","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kz-gedenkstaette-dachau.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.kz-gedenkstaette-dachau.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.kz-gedenkstaette-dachau.de\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kz-gedenkstaette-dachau.de\/en\/wp-json\/wp\/v2\/comments?post=3502"}],"version-history":[{"count":0,"href":"https:\/\/www.kz-gedenkstaette-dachau.de\/en\/wp-json\/wp\/v2\/posts\/3502\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.kz-gedenkstaette-dachau.de\/en\/wp-json\/wp\/v2\/media?parent=3502"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kz-gedenkstaette-dachau.de\/en\/wp-json\/wp\/v2\/categories?post=3502"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kz-gedenkstaette-dachau.de\/en\/wp-json\/wp\/v2\/tags?post=3502"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}