{"id":66836,"date":"2019-10-16T08:06:46","date_gmt":"2019-10-16T06:06:46","guid":{"rendered":"https:\/\/www.kz-gedenkstaette-dachau.de\/rundgangsbroschuere-in-leichter-sprache\/"},"modified":"2020-04-20T16:22:41","modified_gmt":"2020-04-20T14:22:41","slug":"tour-brochure-in-simple-language","status":"publish","type":"post","link":"https:\/\/www.kz-gedenkstaette-dachau.de\/en\/projects\/tour-brochure-in-simple-language\/","title":{"rendered":"Tour Brochure in Simple Language"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":55827,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[21],"tags":[],"class_list":["post-66836","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-projects"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tour Brochure in Simple Language - KZ Gedenkst\u00e4tte Dachau<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.kz-gedenkstaette-dachau.de\/en\/projects\/tour-brochure-in-simple-language\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tour Brochure in Simple Language - KZ Gedenkst\u00e4tte Dachau\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.kz-gedenkstaette-dachau.de\/en\/projects\/tour-brochure-in-simple-language\/\" \/>\n<meta property=\"og:site_name\" content=\"KZ Gedenkst\u00e4tte Dachau\" \/>\n<meta property=\"article:published_time\" content=\"2019-10-16T06:06:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-04-20T14:22:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.kz-gedenkstaette-dachau.de\/wp-content\/uploads\/2019\/10\/NL9_Rundgangsbroschuere-Leichte-Sprache-8b88b7be.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"120\" \/>\n\t<meta property=\"og:image:height\" content=\"170\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"neodesign\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"neodesign\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.kz-gedenkstaette-dachau.de\\\/en\\\/projects\\\/tour-brochure-in-simple-language\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.kz-gedenkstaette-dachau.de\\\/en\\\/projects\\\/tour-brochure-in-simple-language\\\/\"},\"author\":{\"name\":\"neodesign\",\"@id\":\"https:\\\/\\\/www.kz-gedenkstaette-dachau.de\\\/#\\\/schema\\\/person\\\/24134f889baf12937f773e1ef2ed9b39\"},\"headline\":\"Tour Brochure in Simple Language\",\"datePublished\":\"2019-10-16T06:06:46+00:00\",\"dateModified\":\"2020-04-20T14:22:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.kz-gedenkstaette-dachau.de\\\/en\\\/projects\\\/tour-brochure-in-simple-language\\\/\"},\"wordCount\":5,\"image\":{\"@id\":\"https:\\\/\\\/www.kz-gedenkstaette-dachau.de\\\/en\\\/projects\\\/tour-brochure-in-simple-language\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.kz-gedenkstaette-dachau.de\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/NL9_Rundgangsbroschuere-Leichte-Sprache-8b88b7be.jpg\",\"articleSection\":[\"Projects\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.kz-gedenkstaette-dachau.de\\\/en\\\/projects\\\/tour-brochure-in-simple-language\\\/\",\"url\":\"https:\\\/\\\/www.kz-gedenkstaette-dachau.de\\\/en\\\/projects\\\/tour-brochure-in-simple-language\\\/\",\"name\":\"Tour Brochure in Simple Language - KZ Gedenkst\u00e4tte Dachau\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.kz-gedenkstaette-dachau.de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.kz-gedenkstaette-dachau.de\\\/en\\\/projects\\\/tour-brochure-in-simple-language\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kz-gedenkstaette-dachau.de\\\/en\\\/projects\\\/tour-brochure-in-simple-language\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.kz-gedenkstaette-dachau.de\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/NL9_Rundgangsbroschuere-Leichte-Sprache-8b88b7be.jpg\",\"datePublished\":\"2019-10-16T06:06:46+00:00\",\"dateModified\":\"2020-04-20T14:22:41+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.kz-gedenkstaette-dachau.de\\\/#\\\/schema\\\/person\\\/24134f889baf12937f773e1ef2ed9b39\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.kz-gedenkstaette-dachau.de\\\/en\\\/projects\\\/tour-brochure-in-simple-language\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.kz-gedenkstaette-dachau.de\\\/en\\\/projects\\\/tour-brochure-in-simple-language\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.kz-gedenkstaette-dachau.de\\\/en\\\/projects\\\/tour-brochure-in-simple-language\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.kz-gedenkstaette-dachau.de\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/NL9_Rundgangsbroschuere-Leichte-Sprache-8b88b7be.jpg\",\"contentUrl\":\"https:\\\/\\\/www.kz-gedenkstaette-dachau.de\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/NL9_Rundgangsbroschuere-Leichte-Sprache-8b88b7be.jpg\",\"width\":120,\"height\":170},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.kz-gedenkstaette-dachau.de\\\/en\\\/projects\\\/tour-brochure-in-simple-language\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.kz-gedenkstaette-dachau.de\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tour Brochure in Simple Language\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.kz-gedenkstaette-dachau.de\\\/#website\",\"url\":\"https:\\\/\\\/www.kz-gedenkstaette-dachau.de\\\/\",\"name\":\"KZ Gedenkst\u00e4tte Dachau\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.kz-gedenkstaette-dachau.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.kz-gedenkstaette-dachau.de\\\/#\\\/schema\\\/person\\\/24134f889baf12937f773e1ef2ed9b39\",\"name\":\"neodesign\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/048463e9658ed41af53c71679c66426fb09feff4cf8eaa91ccda42ad67530851?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/048463e9658ed41af53c71679c66426fb09feff4cf8eaa91ccda42ad67530851?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/048463e9658ed41af53c71679c66426fb09feff4cf8eaa91ccda42ad67530851?s=96&d=mm&r=g\",\"caption\":\"neodesign\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tour Brochure in Simple Language - KZ Gedenkst\u00e4tte Dachau","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.kz-gedenkstaette-dachau.de\/en\/projects\/tour-brochure-in-simple-language\/","og_locale":"en_US","og_type":"article","og_title":"Tour Brochure in Simple Language - KZ Gedenkst\u00e4tte Dachau","og_url":"https:\/\/www.kz-gedenkstaette-dachau.de\/en\/projects\/tour-brochure-in-simple-language\/","og_site_name":"KZ Gedenkst\u00e4tte Dachau","article_published_time":"2019-10-16T06:06:46+00:00","article_modified_time":"2020-04-20T14:22:41+00:00","og_image":[{"width":120,"height":170,"url":"https:\/\/www.kz-gedenkstaette-dachau.de\/wp-content\/uploads\/2019\/10\/NL9_Rundgangsbroschuere-Leichte-Sprache-8b88b7be.jpg","type":"image\/jpeg"}],"author":"neodesign","twitter_card":"summary_large_image","twitter_misc":{"Written by":"neodesign"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.kz-gedenkstaette-dachau.de\/en\/projects\/tour-brochure-in-simple-language\/#article","isPartOf":{"@id":"https:\/\/www.kz-gedenkstaette-dachau.de\/en\/projects\/tour-brochure-in-simple-language\/"},"author":{"name":"neodesign","@id":"https:\/\/www.kz-gedenkstaette-dachau.de\/#\/schema\/person\/24134f889baf12937f773e1ef2ed9b39"},"headline":"Tour Brochure in Simple Language","datePublished":"2019-10-16T06:06:46+00:00","dateModified":"2020-04-20T14:22:41+00:00","mainEntityOfPage":{"@id":"https:\/\/www.kz-gedenkstaette-dachau.de\/en\/projects\/tour-brochure-in-simple-language\/"},"wordCount":5,"image":{"@id":"https:\/\/www.kz-gedenkstaette-dachau.de\/en\/projects\/tour-brochure-in-simple-language\/#primaryimage"},"thumbnailUrl":"https:\/\/www.kz-gedenkstaette-dachau.de\/wp-content\/uploads\/2019\/10\/NL9_Rundgangsbroschuere-Leichte-Sprache-8b88b7be.jpg","articleSection":["Projects"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.kz-gedenkstaette-dachau.de\/en\/projects\/tour-brochure-in-simple-language\/","url":"https:\/\/www.kz-gedenkstaette-dachau.de\/en\/projects\/tour-brochure-in-simple-language\/","name":"Tour Brochure in Simple Language - KZ Gedenkst\u00e4tte Dachau","isPartOf":{"@id":"https:\/\/www.kz-gedenkstaette-dachau.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.kz-gedenkstaette-dachau.de\/en\/projects\/tour-brochure-in-simple-language\/#primaryimage"},"image":{"@id":"https:\/\/www.kz-gedenkstaette-dachau.de\/en\/projects\/tour-brochure-in-simple-language\/#primaryimage"},"thumbnailUrl":"https:\/\/www.kz-gedenkstaette-dachau.de\/wp-content\/uploads\/2019\/10\/NL9_Rundgangsbroschuere-Leichte-Sprache-8b88b7be.jpg","datePublished":"2019-10-16T06:06:46+00:00","dateModified":"2020-04-20T14:22:41+00:00","author":{"@id":"https:\/\/www.kz-gedenkstaette-dachau.de\/#\/schema\/person\/24134f889baf12937f773e1ef2ed9b39"},"breadcrumb":{"@id":"https:\/\/www.kz-gedenkstaette-dachau.de\/en\/projects\/tour-brochure-in-simple-language\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.kz-gedenkstaette-dachau.de\/en\/projects\/tour-brochure-in-simple-language\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.kz-gedenkstaette-dachau.de\/en\/projects\/tour-brochure-in-simple-language\/#primaryimage","url":"https:\/\/www.kz-gedenkstaette-dachau.de\/wp-content\/uploads\/2019\/10\/NL9_Rundgangsbroschuere-Leichte-Sprache-8b88b7be.jpg","contentUrl":"https:\/\/www.kz-gedenkstaette-dachau.de\/wp-content\/uploads\/2019\/10\/NL9_Rundgangsbroschuere-Leichte-Sprache-8b88b7be.jpg","width":120,"height":170},{"@type":"BreadcrumbList","@id":"https:\/\/www.kz-gedenkstaette-dachau.de\/en\/projects\/tour-brochure-in-simple-language\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.kz-gedenkstaette-dachau.de\/en\/"},{"@type":"ListItem","position":2,"name":"Tour Brochure in Simple Language"}]},{"@type":"WebSite","@id":"https:\/\/www.kz-gedenkstaette-dachau.de\/#website","url":"https:\/\/www.kz-gedenkstaette-dachau.de\/","name":"KZ Gedenkst\u00e4tte Dachau","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.kz-gedenkstaette-dachau.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.kz-gedenkstaette-dachau.de\/#\/schema\/person\/24134f889baf12937f773e1ef2ed9b39","name":"neodesign","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/048463e9658ed41af53c71679c66426fb09feff4cf8eaa91ccda42ad67530851?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/048463e9658ed41af53c71679c66426fb09feff4cf8eaa91ccda42ad67530851?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/048463e9658ed41af53c71679c66426fb09feff4cf8eaa91ccda42ad67530851?s=96&d=mm&r=g","caption":"neodesign"}}]}},"_links":{"self":[{"href":"https:\/\/www.kz-gedenkstaette-dachau.de\/en\/wp-json\/wp\/v2\/posts\/66836","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kz-gedenkstaette-dachau.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.kz-gedenkstaette-dachau.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.kz-gedenkstaette-dachau.de\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kz-gedenkstaette-dachau.de\/en\/wp-json\/wp\/v2\/comments?post=66836"}],"version-history":[{"count":0,"href":"https:\/\/www.kz-gedenkstaette-dachau.de\/en\/wp-json\/wp\/v2\/posts\/66836\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kz-gedenkstaette-dachau.de\/en\/wp-json\/wp\/v2\/media\/55827"}],"wp:attachment":[{"href":"https:\/\/www.kz-gedenkstaette-dachau.de\/en\/wp-json\/wp\/v2\/media?parent=66836"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kz-gedenkstaette-dachau.de\/en\/wp-json\/wp\/v2\/categories?post=66836"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kz-gedenkstaette-dachau.de\/en\/wp-json\/wp\/v2\/tags?post=66836"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}