{"id":79617,"date":"2022-01-21T13:21:51","date_gmt":"2022-01-21T12:21:51","guid":{"rendered":"https:\/\/www.kz-gedenkstaette-dachau.de\/uncategorized\/biografie-rudolf-heinrich-suttrop-id-7\/"},"modified":"2022-04-26T22:04:57","modified_gmt":"2022-04-26T20:04:57","slug":"biografie-rudolf-heinrich-suttrop-id-7","status":"publish","type":"post","link":"https:\/\/www.kz-gedenkstaette-dachau.de\/en\/sonderausstellung-dachauer-prozesse-en\/biografien-en\/biografie-rudolf-heinrich-suttrop-id-7\/","title":{"rendered":"Biography: Rudolf Heinrich Suttrop"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":45,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[724,725],"tags":[],"class_list":["post-79617","post","type-post","status-publish","format-standard","hentry","category-biografien-en","category-sonderausstellung-dachauer-prozesse-en"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Biography: Rudolf Heinrich Suttrop - KZ Gedenkst\u00e4tte Dachau<\/title>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Biography: Rudolf Heinrich Suttrop - KZ Gedenkst\u00e4tte Dachau\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.kz-gedenkstaette-dachau.de\/en\/biografien-en\/biografie-rudolf-heinrich-suttrop-id-7\/\" \/>\n<meta property=\"og:site_name\" content=\"KZ Gedenkst\u00e4tte Dachau\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-21T12:21:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-04-26T20:04:57+00:00\" \/>\n<meta name=\"author\" content=\"Website-Archiv\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Website-Archiv\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.kz-gedenkstaette-dachau.de\\\/en\\\/biografien-en\\\/biografie-rudolf-heinrich-suttrop-id-7\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.kz-gedenkstaette-dachau.de\\\/en\\\/biografien-en\\\/biografie-rudolf-heinrich-suttrop-id-7\\\/\"},\"author\":{\"name\":\"Website-Archiv\",\"@id\":\"https:\\\/\\\/www.kz-gedenkstaette-dachau.de\\\/#\\\/schema\\\/person\\\/c7964160f4c0d409a445e7ad3faa033f\"},\"headline\":\"Biography: Rudolf Heinrich Suttrop\",\"datePublished\":\"2022-01-21T12:21:51+00:00\",\"dateModified\":\"2022-04-26T20:04:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.kz-gedenkstaette-dachau.de\\\/en\\\/biografien-en\\\/biografie-rudolf-heinrich-suttrop-id-7\\\/\"},\"wordCount\":4,\"articleSection\":[\"Biografien\",\"Sonderausstellung Dachauer Prozesse\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.kz-gedenkstaette-dachau.de\\\/en\\\/biografien-en\\\/biografie-rudolf-heinrich-suttrop-id-7\\\/\",\"url\":\"https:\\\/\\\/www.kz-gedenkstaette-dachau.de\\\/en\\\/biografien-en\\\/biografie-rudolf-heinrich-suttrop-id-7\\\/\",\"name\":\"Biography: Rudolf Heinrich Suttrop - KZ Gedenkst\u00e4tte Dachau\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.kz-gedenkstaette-dachau.de\\\/#website\"},\"datePublished\":\"2022-01-21T12:21:51+00:00\",\"dateModified\":\"2022-04-26T20:04:57+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.kz-gedenkstaette-dachau.de\\\/#\\\/schema\\\/person\\\/c7964160f4c0d409a445e7ad3faa033f\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.kz-gedenkstaette-dachau.de\\\/en\\\/biografien-en\\\/biografie-rudolf-heinrich-suttrop-id-7\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.kz-gedenkstaette-dachau.de\\\/en\\\/biografien-en\\\/biografie-rudolf-heinrich-suttrop-id-7\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.kz-gedenkstaette-dachau.de\\\/en\\\/biografien-en\\\/biografie-rudolf-heinrich-suttrop-id-7\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.kz-gedenkstaette-dachau.de\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Biography: Rudolf Heinrich Suttrop\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.kz-gedenkstaette-dachau.de\\\/#website\",\"url\":\"https:\\\/\\\/www.kz-gedenkstaette-dachau.de\\\/\",\"name\":\"KZ Gedenkst\u00e4tte Dachau\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.kz-gedenkstaette-dachau.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.kz-gedenkstaette-dachau.de\\\/#\\\/schema\\\/person\\\/c7964160f4c0d409a445e7ad3faa033f\",\"name\":\"Website-Archiv\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/13393da9a6f21e9fed25f2f538afbc7f9eebdad16fc8dcb2624b6f957d55c677?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/13393da9a6f21e9fed25f2f538afbc7f9eebdad16fc8dcb2624b6f957d55c677?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/13393da9a6f21e9fed25f2f538afbc7f9eebdad16fc8dcb2624b6f957d55c677?s=96&d=mm&r=g\",\"caption\":\"Website-Archiv\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Biography: Rudolf Heinrich Suttrop - KZ Gedenkst\u00e4tte Dachau","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"en_US","og_type":"article","og_title":"Biography: Rudolf Heinrich Suttrop - KZ Gedenkst\u00e4tte Dachau","og_url":"https:\/\/www.kz-gedenkstaette-dachau.de\/en\/biografien-en\/biografie-rudolf-heinrich-suttrop-id-7\/","og_site_name":"KZ Gedenkst\u00e4tte Dachau","article_published_time":"2022-01-21T12:21:51+00:00","article_modified_time":"2022-04-26T20:04:57+00:00","author":"Website-Archiv","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Website-Archiv"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.kz-gedenkstaette-dachau.de\/en\/biografien-en\/biografie-rudolf-heinrich-suttrop-id-7\/#article","isPartOf":{"@id":"https:\/\/www.kz-gedenkstaette-dachau.de\/en\/biografien-en\/biografie-rudolf-heinrich-suttrop-id-7\/"},"author":{"name":"Website-Archiv","@id":"https:\/\/www.kz-gedenkstaette-dachau.de\/#\/schema\/person\/c7964160f4c0d409a445e7ad3faa033f"},"headline":"Biography: Rudolf Heinrich Suttrop","datePublished":"2022-01-21T12:21:51+00:00","dateModified":"2022-04-26T20:04:57+00:00","mainEntityOfPage":{"@id":"https:\/\/www.kz-gedenkstaette-dachau.de\/en\/biografien-en\/biografie-rudolf-heinrich-suttrop-id-7\/"},"wordCount":4,"articleSection":["Biografien","Sonderausstellung Dachauer Prozesse"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.kz-gedenkstaette-dachau.de\/en\/biografien-en\/biografie-rudolf-heinrich-suttrop-id-7\/","url":"https:\/\/www.kz-gedenkstaette-dachau.de\/en\/biografien-en\/biografie-rudolf-heinrich-suttrop-id-7\/","name":"Biography: Rudolf Heinrich Suttrop - KZ Gedenkst\u00e4tte Dachau","isPartOf":{"@id":"https:\/\/www.kz-gedenkstaette-dachau.de\/#website"},"datePublished":"2022-01-21T12:21:51+00:00","dateModified":"2022-04-26T20:04:57+00:00","author":{"@id":"https:\/\/www.kz-gedenkstaette-dachau.de\/#\/schema\/person\/c7964160f4c0d409a445e7ad3faa033f"},"breadcrumb":{"@id":"https:\/\/www.kz-gedenkstaette-dachau.de\/en\/biografien-en\/biografie-rudolf-heinrich-suttrop-id-7\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.kz-gedenkstaette-dachau.de\/en\/biografien-en\/biografie-rudolf-heinrich-suttrop-id-7\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.kz-gedenkstaette-dachau.de\/en\/biografien-en\/biografie-rudolf-heinrich-suttrop-id-7\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.kz-gedenkstaette-dachau.de\/en\/"},{"@type":"ListItem","position":2,"name":"Biography: Rudolf Heinrich Suttrop"}]},{"@type":"WebSite","@id":"https:\/\/www.kz-gedenkstaette-dachau.de\/#website","url":"https:\/\/www.kz-gedenkstaette-dachau.de\/","name":"KZ Gedenkst\u00e4tte Dachau","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.kz-gedenkstaette-dachau.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.kz-gedenkstaette-dachau.de\/#\/schema\/person\/c7964160f4c0d409a445e7ad3faa033f","name":"Website-Archiv","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/13393da9a6f21e9fed25f2f538afbc7f9eebdad16fc8dcb2624b6f957d55c677?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/13393da9a6f21e9fed25f2f538afbc7f9eebdad16fc8dcb2624b6f957d55c677?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/13393da9a6f21e9fed25f2f538afbc7f9eebdad16fc8dcb2624b6f957d55c677?s=96&d=mm&r=g","caption":"Website-Archiv"}}]}},"_links":{"self":[{"href":"https:\/\/www.kz-gedenkstaette-dachau.de\/en\/wp-json\/wp\/v2\/posts\/79617","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kz-gedenkstaette-dachau.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.kz-gedenkstaette-dachau.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.kz-gedenkstaette-dachau.de\/en\/wp-json\/wp\/v2\/users\/45"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kz-gedenkstaette-dachau.de\/en\/wp-json\/wp\/v2\/comments?post=79617"}],"version-history":[{"count":3,"href":"https:\/\/www.kz-gedenkstaette-dachau.de\/en\/wp-json\/wp\/v2\/posts\/79617\/revisions"}],"predecessor-version":[{"id":79887,"href":"https:\/\/www.kz-gedenkstaette-dachau.de\/en\/wp-json\/wp\/v2\/posts\/79617\/revisions\/79887"}],"wp:attachment":[{"href":"https:\/\/www.kz-gedenkstaette-dachau.de\/en\/wp-json\/wp\/v2\/media?parent=79617"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kz-gedenkstaette-dachau.de\/en\/wp-json\/wp\/v2\/categories?post=79617"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kz-gedenkstaette-dachau.de\/en\/wp-json\/wp\/v2\/tags?post=79617"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}