{"id":65876,"date":"2018-08-30T15:00:41","date_gmt":"2018-08-30T13:00:41","guid":{"rendered":"https:\/\/www.kz-gedenkstaette-dachau.de\/data-privacy\/"},"modified":"2024-11-12T17:03:26","modified_gmt":"2024-11-12T16:03:26","slug":"data-privacy","status":"publish","type":"page","link":"https:\/\/www.kz-gedenkstaette-dachau.de\/it\/data-privacy\/","title":{"rendered":"Data privacy statement"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":9000,"comment_status":"closed","ping_status":"closed","template":"page-informationsseite.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-65876","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Data privacy statement - KZ Gedenkst\u00e4tte Dachau<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.kz-gedenkstaette-dachau.de\/it\/data-privacy\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Data privacy statement - KZ Gedenkst\u00e4tte Dachau\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.kz-gedenkstaette-dachau.de\/it\/data-privacy\/\" \/>\n<meta property=\"og:site_name\" content=\"KZ Gedenkst\u00e4tte Dachau\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-12T16:03:26+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.kz-gedenkstaette-dachau.de\\\/it\\\/data-privacy\\\/\",\"url\":\"https:\\\/\\\/www.kz-gedenkstaette-dachau.de\\\/it\\\/data-privacy\\\/\",\"name\":\"Data privacy statement - KZ Gedenkst\u00e4tte Dachau\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.kz-gedenkstaette-dachau.de\\\/#website\"},\"datePublished\":\"2018-08-30T13:00:41+00:00\",\"dateModified\":\"2024-11-12T16:03:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.kz-gedenkstaette-dachau.de\\\/it\\\/data-privacy\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.kz-gedenkstaette-dachau.de\\\/it\\\/data-privacy\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.kz-gedenkstaette-dachau.de\\\/it\\\/data-privacy\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Pagina principale\",\"item\":\"https:\\\/\\\/www.kz-gedenkstaette-dachau.de\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Data privacy statement\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.kz-gedenkstaette-dachau.de\\\/#website\",\"url\":\"https:\\\/\\\/www.kz-gedenkstaette-dachau.de\\\/\",\"name\":\"KZ Gedenkst\u00e4tte Dachau\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.kz-gedenkstaette-dachau.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Data privacy statement - KZ Gedenkst\u00e4tte Dachau","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.kz-gedenkstaette-dachau.de\/it\/data-privacy\/","og_locale":"it_IT","og_type":"article","og_title":"Data privacy statement - KZ Gedenkst\u00e4tte Dachau","og_url":"https:\/\/www.kz-gedenkstaette-dachau.de\/it\/data-privacy\/","og_site_name":"KZ Gedenkst\u00e4tte Dachau","article_modified_time":"2024-11-12T16:03:26+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.kz-gedenkstaette-dachau.de\/it\/data-privacy\/","url":"https:\/\/www.kz-gedenkstaette-dachau.de\/it\/data-privacy\/","name":"Data privacy statement - KZ Gedenkst\u00e4tte Dachau","isPartOf":{"@id":"https:\/\/www.kz-gedenkstaette-dachau.de\/#website"},"datePublished":"2018-08-30T13:00:41+00:00","dateModified":"2024-11-12T16:03:26+00:00","breadcrumb":{"@id":"https:\/\/www.kz-gedenkstaette-dachau.de\/it\/data-privacy\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.kz-gedenkstaette-dachau.de\/it\/data-privacy\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.kz-gedenkstaette-dachau.de\/it\/data-privacy\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Pagina principale","item":"https:\/\/www.kz-gedenkstaette-dachau.de\/it\/"},{"@type":"ListItem","position":2,"name":"Data privacy statement"}]},{"@type":"WebSite","@id":"https:\/\/www.kz-gedenkstaette-dachau.de\/#website","url":"https:\/\/www.kz-gedenkstaette-dachau.de\/","name":"KZ Gedenkst\u00e4tte Dachau","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.kz-gedenkstaette-dachau.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/www.kz-gedenkstaette-dachau.de\/it\/wp-json\/wp\/v2\/pages\/65876","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kz-gedenkstaette-dachau.de\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.kz-gedenkstaette-dachau.de\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.kz-gedenkstaette-dachau.de\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kz-gedenkstaette-dachau.de\/it\/wp-json\/wp\/v2\/comments?post=65876"}],"version-history":[{"count":3,"href":"https:\/\/www.kz-gedenkstaette-dachau.de\/it\/wp-json\/wp\/v2\/pages\/65876\/revisions"}],"predecessor-version":[{"id":94437,"href":"https:\/\/www.kz-gedenkstaette-dachau.de\/it\/wp-json\/wp\/v2\/pages\/65876\/revisions\/94437"}],"wp:attachment":[{"href":"https:\/\/www.kz-gedenkstaette-dachau.de\/it\/wp-json\/wp\/v2\/media?parent=65876"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}